{"id":8748,"date":"2023-06-24T08:00:00","date_gmt":"2023-06-24T07:00:00","guid":{"rendered":"https:\/\/www2.ual.es\/neotrie\/?post_type=project&#038;p=8748"},"modified":"2026-05-27T11:49:43","modified_gmt":"2026-05-27T10:49:43","slug":"aprendizaje-de-los-cuadrilateros-a-traves-del-3d","status":"publish","type":"project","link":"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/","title":{"rendered":"Aprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D"},"content":{"rendered":"\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Coordinadora<\/strong>: Carmen Santos Morales Rodr\u00edguez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto que a continuaci\u00f3n se presenta, <strong>pretende ofrecer una secuencia de actividades para trabajar el contenido de los cuadril\u00e1teros <\/strong> en 4\u00ba, 5\u00ba y 6\u00ba de Educaci\u00f3n Primaria a trav\u00e9s de actividades de observaci\u00f3n, interacci\u00f3n din\u00e1mica y an\u00e1lisis de objetos 3D virtuales que requieren poner en pr\u00e1ctica sus propias habilidades de construcci\u00f3n, observaci\u00f3n, manipulaci\u00f3n, descripci\u00f3n y clasificaci\u00f3n, todo ello en un ambiente de trabajo cooperativo y kinest\u00e9sico grupal <strong>que mejore su motivaci\u00f3n y a su vez fomente el uso espont\u00e1neo del lenguaje matem\u00e1tico y el desarrollo de habilidades espaciales para la identificaci\u00f3n y comprensi\u00f3n de las principales caracter\u00edsticas de los s\u00f3lidos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Respecto al dominio cient\u00edfico de la geometr\u00eda, y m\u00e1s concretamente sobre cuadril\u00e1teros y figuras tridimensionales, centramos nuestro trabajo en las siguientes <strong>competencias espec\u00edficas y saberes b\u00e1sicos<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Competencia espec\u00edfica 1.2.a. Comenzar a elaborar y mostrar representaciones matem\u00e1ticas que ayuden en la b\u00fasqueda y elecci\u00f3n de estrategias y herramientas, incluidas las tecnol\u00f3gicas, para la resoluci\u00f3n de una situaci\u00f3n problematizada medioambiental o social, individualmente y cooperando entre iguales, comenzando a desarrollar una actitud de implicaci\u00f3n.<\/li>\n\n\n\n<li>Competencia espec\u00edfica 4.2.a. Comenzar a emplear herramientas&nbsp; tecnol\u00f3gicas adecuadas en la investigaci\u00f3n y resoluci\u00f3n de problemas.<\/li>\n\n\n\n<li>Competencia espec\u00edfica 6.1.a. Comenzar a interpretar el lenguaje matem\u00e1tico sencillo presente en la vida cotidiana en diferentes formatos, adquiriendo vocabulario apropiado, utilizando este lenguaje para expresar ideas matem\u00e1ticas, mostrando comprensi\u00f3n del mensaje.<\/li>\n\n\n\n<li>Competencia espec\u00edfica 6.2.a. Comenzar a comunicar en diferentes formatos las conjeturas y procesos matem\u00e1ticos, utilizando lenguaje matem\u00e1tico adecuado, con el prop\u00f3sito de transmitir informaci\u00f3n matem\u00e1tica.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Saber b\u00e1sico C. Sentido espacial:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>MA.03.C.1. Figuras geom\u00e9tricas de dos y tres dimensiones.<\/li>\n\n\n\n<li>MA.03.C.1.2. T\u00e9cnicas de construcci\u00f3n de figuras geom\u00e9tricas por composici\u00f3n y descomposici\u00f3n, mediante materiales manipulables, instrumentos de dibujo y aplicaciones inform\u00e1ticas.<\/li>\n\n\n\n<li>MA.03.C.1.3. Vocabulario geom\u00e9trico: descripci\u00f3n verbal de los elementos y las propiedades de figuras geom\u00e9tricas.<\/li>\n\n\n\n<li>MA.03.C.1.4. Propiedades de figuras geom\u00e9tricas: exploraci\u00f3n mediante materiales manipulables y l\u00fadicos (cuadr\u00edculas, geoplanos, policubos, magia educativa, etc.) y herramientas digitales (programas de geometr\u00eda din\u00e1mica, realidad aumentada, rob\u00f3tica educativa, etc.).<\/li>\n\n\n\n<li>MA.03.C.4. Visualizaci\u00f3n, razonamiento y modelizaci\u00f3n geom\u00e9trica.<\/li>\n\n\n\n<li>MA.03.C.4.3. Elaboraci\u00f3n de conjeturas sobre propiedades geom\u00e9tricas utilizando instrumentos de dibujo (comp\u00e1s y transportador de \u00e1ngulos) y programas de geometr\u00eda din\u00e1mica.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Previo al trabajo con Neotrie VR, se induce la definici\u00f3n de paralelismo, perpendicularidad, cuadril\u00e1tero, prisma, paralelogramo y pol\u00edgono respectivamente. Comienza el\/la docente clasificando la primera forma o figura, sin definiciones. Contin\u00faa el alumnado observando, justificando y agrupando las siguientes, seg\u00fan las similitudes y diferencias de los elementos presentes en el material manipulable e im\u00e1genes que se les presenta cuidando la elecci\u00f3n de ejemplos y contraejemplos. Se dirige su atenci\u00f3n a trav\u00e9s de preguntas para llegar a construir sus propias definiciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lecciones<\/strong> en las que se divide la secuencia did\u00e1ctica:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Iniciaci\u00f3n a NeoTrie VR.<\/li>\n\n\n\n<li><a href=\"https:\/\/www2.ual.es\/neotrie\/creando-la-nocion-de-paralelismo-y-perpendicularidad-en-3d\/\" target=\"_blank\" rel=\"noopener\" title=\"Creando la noci\u00f3n de paralelismo y perpendicularidad.\">Creando la noci\u00f3n de paralelismo y perpendicularidad.<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www2.ual.es\/neotrie\/hacia-la-nocion-de-cuadrilatero\/\" target=\"_blank\" rel=\"noopener\" title=\"Hacia la noci\u00f3n de cuadril\u00e1tero.\">Hacia la noci\u00f3n de cuadril\u00e1tero.<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www2.ual.es\/neotrie\/extrusion-de-1d-a-2d-y-de-2d-a-3d\/\" target=\"_blank\" rel=\"noopener\" title=\"Extrusi\u00f3n de 1D a 2D y de 2D a 3D.\">Extrusi\u00f3n de 1D a 2D y de 2D a 3D.<\/a><a href=\"https:\/\/www2.ual.es\/neotrie\/juegos-con-cuadrilateros\/\" target=\"_blank\" rel=\"noopener\" title=\" Juegos de extrusi\u00f3n.\"> Juegos de extrusi\u00f3n.<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/\" target=\"_blank\" rel=\"noopener\" title=\"Cortes con el plano. De 3D a 2D.\">Cortes con el plano. De 3D a 2D.<\/a><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Agradecimientos: <em><em>Proyecto de Investigaci\u00f3n educativa PIV-055\/21, de la Junta de Andaluc\u00eda, y Proyecto UAL2020-SEJ-B2086, FEDER-Junta de Andaluc\u00eda. Los resultados de este proyecto se presentar\u00e1n en una <a href=\"https:\/\/www2.ual.es\/neotrie\/wp-content\/uploads\/2023\/06\/COM_aprendizajedeloscuadrilaterosconneotrievrcomorecursoderealidadvirtualinmersiva-copia.pdf\">comunicaci\u00f3n<\/a> en el pr\u00f3ximo <a href=\"https:\/\/thales.cica.es\/xviiiceam\/\">XVIII CEAM<\/a> de Granada.<\/em><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":71,"featured_media":8742,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"project_category":[],"project_tag":[],"class_list":["post-8748","project","type-project","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Coordinadora: Carmen Santos Morales Rodr\u00edguez El proyecto que a continuaci\u00f3n se presenta, pretende ofrecer una secuencia de actividades para trabajar el contenido de los cuadril\u00e1teros en 4\u00ba, 5\u00ba y 6\u00ba de Educaci\u00f3n Primaria a trav\u00e9s de actividades de observaci\u00f3n, interacci\u00f3n din\u00e1mica y an\u00e1lisis de objetos 3D virtuales que requieren poner en pr\u00e1ctica sus propias habilidades\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Carmen Santos Morales Rodr\u00edguez\"\/>\n\t<meta name=\"google-site-verification\" content=\"google-site-verification=yECM5sD2Ii3xsSoDBArqBmNdlDrmXh-FAAOQ40keSr4\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Neotrie VR - NeoTrie VR es un software de realidad virtual y mixta, multijugador, que permite al usuario crear, manipular e interactuar con objetos geom\u00e9tricos y modelos 3D en general.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Aprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D \ufeff \ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff-\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff \ufeffNeotrie VR\" \/>\n\t\t<meta property=\"og:description\" content=\"Coordinadora: Carmen Santos Morales Rodr\u00edguez El proyecto que a continuaci\u00f3n se presenta, pretende ofrecer una secuencia de actividades para trabajar el contenido de los cuadril\u00e1teros en 4\u00ba, 5\u00ba y 6\u00ba de Educaci\u00f3n Primaria a trav\u00e9s de actividades de observaci\u00f3n, interacci\u00f3n din\u00e1mica y an\u00e1lisis de objetos 3D virtuales que requieren poner en pr\u00e1ctica sus propias habilidades\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-06-24T07:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-05-27T10:49:43+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/neotrie\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NeotrieVR\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Aprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D \ufeff \ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff-\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff \ufeffNeotrie VR\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Coordinadora: Carmen Santos Morales Rodr\u00edguez El proyecto que a continuaci\u00f3n se presenta, pretende ofrecer una secuencia de actividades para trabajar el contenido de los cuadril\u00e1teros en 4\u00ba, 5\u00ba y 6\u00ba de Educaci\u00f3n Primaria a trav\u00e9s de actividades de observaci\u00f3n, interacci\u00f3n din\u00e1mica y an\u00e1lisis de objetos 3D virtuales que requieren poner en pr\u00e1ctica sus propias habilidades\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@NeotrieVR\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/project\\\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/project\\\/#listItem\",\"name\":\"Projects\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/project\\\/#listItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/project\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/project\\\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\\\/#listItem\",\"name\":\"Aprendizaje de los cuadril\\u00e1teros a trav\\u00e9s del 3D\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/project\\\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\\\/#listItem\",\"position\":3,\"name\":\"Aprendizaje de los cuadril\\u00e1teros a trav\\u00e9s del 3D\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/project\\\/#listItem\",\"name\":\"Projects\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/#organization\",\"name\":\"Neotrie VR\",\"description\":\"NeoTrie VR es un software de realidad virtual y mixta, multijugador, que permite al usuario crear, manipular e interactuar con objetos geom\\u00e9tricos y modelos 3D en general.\",\"url\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/\",\"telephone\":\"+34617666437\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo-Nuevo-NeoTrie-VR.jpeg\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/project\\\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\\\/#organizationLogo\",\"width\":311,\"height\":311},\"image\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/project\\\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/neotrie\",\"https:\\\/\\\/twitter.com\\\/NeotrieVR\",\"https:\\\/\\\/www.instagram.com\\\/neotrievr\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCn7vETd_lSC3ZiT9Xgo4FTA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/author\\\/cmr373\\\/#author\",\"url\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/author\\\/cmr373\\\/\",\"name\":\"Carmen Santos Morales Rodr\\u00edguez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/project\\\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\\\/#authorImage\",\"url\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/wp-content\\\/plugins\\\/ultimate-member\\\/assets\\\/img\\\/default_avatar.jpg\",\"width\":96,\"height\":96,\"caption\":\"Carmen Santos Morales Rodr\\u00edguez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/project\\\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\\\/#webpage\",\"url\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/project\\\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\\\/\",\"name\":\"Aprendizaje de los cuadril\\u00e1teros a trav\\u00e9s del 3D \\ufeff \\ufeff\\ufeff\\ufeff\\ufeff\\ufeff\\ufeff\\ufeff\\ufeff-\\ufeff\\ufeff\\ufeff\\ufeff\\ufeff\\ufeff\\ufeff\\ufeff \\ufeffNeotrie VR\",\"description\":\"Coordinadora: Carmen Santos Morales Rodr\\u00edguez El proyecto que a continuaci\\u00f3n se presenta, pretende ofrecer una secuencia de actividades para trabajar el contenido de los cuadril\\u00e1teros en 4\\u00ba, 5\\u00ba y 6\\u00ba de Educaci\\u00f3n Primaria a trav\\u00e9s de actividades de observaci\\u00f3n, interacci\\u00f3n din\\u00e1mica y an\\u00e1lisis de objetos 3D virtuales que requieren poner en pr\\u00e1ctica sus propias habilidades\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/project\\\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/author\\\/cmr373\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/author\\\/cmr373\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Analizando-figuras-Leccion-3-pixelado.jpg\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/project\\\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\\\/#mainImage\",\"width\":1123,\"height\":672},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/project\\\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\\\/#mainImage\"},\"datePublished\":\"2023-06-24T08:00:00+01:00\",\"dateModified\":\"2026-05-27T11:49:43+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/#website\",\"url\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/\",\"name\":\"Neotrie VR\",\"description\":\"NeoTrie VR es un software de realidad virtual y mixta, multijugador, que permite al usuario crear, manipular e interactuar con objetos geom\\u00e9tricos y modelos 3D en general.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Aprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D \ufeff \ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff-\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff \ufeffNeotrie VR","description":"Coordinadora: Carmen Santos Morales Rodr\u00edguez El proyecto que a continuaci\u00f3n se presenta, pretende ofrecer una secuencia de actividades para trabajar el contenido de los cuadril\u00e1teros en 4\u00ba, 5\u00ba y 6\u00ba de Educaci\u00f3n Primaria a trav\u00e9s de actividades de observaci\u00f3n, interacci\u00f3n din\u00e1mica y an\u00e1lisis de objetos 3D virtuales que requieren poner en pr\u00e1ctica sus propias habilidades","canonical_url":"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"google-site-verification=yECM5sD2Ii3xsSoDBArqBmNdlDrmXh-FAAOQ40keSr4","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www2.ual.es\/neotrie#listItem","position":1,"name":"Inicio","item":"https:\/\/www2.ual.es\/neotrie","nextItem":{"@type":"ListItem","@id":"https:\/\/www2.ual.es\/neotrie\/project\/#listItem","name":"Projects"}},{"@type":"ListItem","@id":"https:\/\/www2.ual.es\/neotrie\/project\/#listItem","position":2,"name":"Projects","item":"https:\/\/www2.ual.es\/neotrie\/project\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/#listItem","name":"Aprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www2.ual.es\/neotrie#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/#listItem","position":3,"name":"Aprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D","previousItem":{"@type":"ListItem","@id":"https:\/\/www2.ual.es\/neotrie\/project\/#listItem","name":"Projects"}}]},{"@type":"Organization","@id":"https:\/\/www2.ual.es\/neotrie\/#organization","name":"Neotrie VR","description":"NeoTrie VR es un software de realidad virtual y mixta, multijugador, que permite al usuario crear, manipular e interactuar con objetos geom\u00e9tricos y modelos 3D en general.","url":"https:\/\/www2.ual.es\/neotrie\/","telephone":"+34617666437","logo":{"@type":"ImageObject","url":"https:\/\/www2.ual.es\/neotrie\/wp-content\/uploads\/2023\/05\/Logo-Nuevo-NeoTrie-VR.jpeg","@id":"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/#organizationLogo","width":311,"height":311},"image":{"@id":"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/neotrie","https:\/\/twitter.com\/NeotrieVR","https:\/\/www.instagram.com\/neotrievr","https:\/\/www.youtube.com\/channel\/UCn7vETd_lSC3ZiT9Xgo4FTA"]},{"@type":"Person","@id":"https:\/\/www2.ual.es\/neotrie\/author\/cmr373\/#author","url":"https:\/\/www2.ual.es\/neotrie\/author\/cmr373\/","name":"Carmen Santos Morales Rodr\u00edguez","image":{"@type":"ImageObject","@id":"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/#authorImage","url":"https:\/\/www2.ual.es\/neotrie\/wp-content\/plugins\/ultimate-member\/assets\/img\/default_avatar.jpg","width":96,"height":96,"caption":"Carmen Santos Morales Rodr\u00edguez"}},{"@type":"WebPage","@id":"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/#webpage","url":"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/","name":"Aprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D \ufeff \ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff-\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff \ufeffNeotrie VR","description":"Coordinadora: Carmen Santos Morales Rodr\u00edguez El proyecto que a continuaci\u00f3n se presenta, pretende ofrecer una secuencia de actividades para trabajar el contenido de los cuadril\u00e1teros en 4\u00ba, 5\u00ba y 6\u00ba de Educaci\u00f3n Primaria a trav\u00e9s de actividades de observaci\u00f3n, interacci\u00f3n din\u00e1mica y an\u00e1lisis de objetos 3D virtuales que requieren poner en pr\u00e1ctica sus propias habilidades","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www2.ual.es\/neotrie\/#website"},"breadcrumb":{"@id":"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/#breadcrumblist"},"author":{"@id":"https:\/\/www2.ual.es\/neotrie\/author\/cmr373\/#author"},"creator":{"@id":"https:\/\/www2.ual.es\/neotrie\/author\/cmr373\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www2.ual.es\/neotrie\/wp-content\/uploads\/2023\/06\/Analizando-figuras-Leccion-3-pixelado.jpg","@id":"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/#mainImage","width":1123,"height":672},"primaryImageOfPage":{"@id":"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/#mainImage"},"datePublished":"2023-06-24T08:00:00+01:00","dateModified":"2026-05-27T11:49:43+01:00"},{"@type":"WebSite","@id":"https:\/\/www2.ual.es\/neotrie\/#website","url":"https:\/\/www2.ual.es\/neotrie\/","name":"Neotrie VR","description":"NeoTrie VR es un software de realidad virtual y mixta, multijugador, que permite al usuario crear, manipular e interactuar con objetos geom\u00e9tricos y modelos 3D en general.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www2.ual.es\/neotrie\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Neotrie VR - NeoTrie VR es un software de realidad virtual y mixta, multijugador, que permite al usuario crear, manipular e interactuar con objetos geom\u00e9tricos y modelos 3D en general.","og:type":"article","og:title":"Aprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D \ufeff \ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff-\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff \ufeffNeotrie VR","og:description":"Coordinadora: Carmen Santos Morales Rodr\u00edguez El proyecto que a continuaci\u00f3n se presenta, pretende ofrecer una secuencia de actividades para trabajar el contenido de los cuadril\u00e1teros en 4\u00ba, 5\u00ba y 6\u00ba de Educaci\u00f3n Primaria a trav\u00e9s de actividades de observaci\u00f3n, interacci\u00f3n din\u00e1mica y an\u00e1lisis de objetos 3D virtuales que requieren poner en pr\u00e1ctica sus propias habilidades","og:url":"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/","article:published_time":"2023-06-24T07:00:00+00:00","article:modified_time":"2026-05-27T10:49:43+00:00","article:publisher":"https:\/\/www.facebook.com\/neotrie","twitter:card":"summary_large_image","twitter:site":"@NeotrieVR","twitter:title":"Aprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D \ufeff \ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff-\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff \ufeffNeotrie VR","twitter:description":"Coordinadora: Carmen Santos Morales Rodr\u00edguez El proyecto que a continuaci\u00f3n se presenta, pretende ofrecer una secuencia de actividades para trabajar el contenido de los cuadril\u00e1teros en 4\u00ba, 5\u00ba y 6\u00ba de Educaci\u00f3n Primaria a trav\u00e9s de actividades de observaci\u00f3n, interacci\u00f3n din\u00e1mica y an\u00e1lisis de objetos 3D virtuales que requieren poner en pr\u00e1ctica sus propias habilidades","twitter:creator":"@NeotrieVR"},"aioseo_meta_data":{"post_id":"8748","title":"#post_title \ufeff \ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff#separator_sa\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff\ufeff \ufeff#site_title","description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-06-27 17:59:34","updated":"2026-05-27 11:49:26","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www2.ual.es\/neotrie\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www2.ual.es\/neotrie\/project\/\" title=\"Projects\">Projects<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www2.ual.es\/neotrie"},{"label":"Projects","link":"https:\/\/www2.ual.es\/neotrie\/project\/"},{"label":"Aprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D","link":"https:\/\/www2.ual.es\/neotrie\/project\/aprendizaje-de-los-cuadrilateros-a-traves-del-3d\/"}],"_links":{"self":[{"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/project\/8748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/users\/71"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/comments?post=8748"}],"version-history":[{"count":13,"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/project\/8748\/revisions"}],"predecessor-version":[{"id":11932,"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/project\/8748\/revisions\/11932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/media\/8742"}],"wp:attachment":[{"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/media?parent=8748"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/project_category?post=8748"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/project_tag?post=8748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}