{"id":8790,"date":"2023-06-29T20:45:49","date_gmt":"2023-06-29T19:45:49","guid":{"rendered":"https:\/\/www2.ual.es\/neotrie\/?p=8790"},"modified":"2026-05-27T11:47:43","modified_gmt":"2026-05-27T10:47:43","slug":"cortes-con-el-plano-de-3d-a-2d","status":"publish","type":"post","link":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/","title":{"rendered":"Cortes con el plano. De 3D a 2D."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Esta actividad forma parte del proyecto \u201c<a href=\"https:\/\/www2.ual.es\/neotrie\/?post_type=project&amp;p=8748\">Aprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D<\/a>\u201c.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"489\" height=\"445\" src=\"https:\/\/www2.ual.es\/neotrie\/wp-content\/uploads\/2023\/06\/Vertices-resultantes-de-la-interseccion-.jpg\" alt=\"\" class=\"wp-image-8791\" srcset=\"https:\/\/www2.ual.es\/neotrie\/wp-content\/uploads\/2023\/06\/Vertices-resultantes-de-la-interseccion-.jpg 489w, https:\/\/www2.ual.es\/neotrie\/wp-content\/uploads\/2023\/06\/Vertices-resultantes-de-la-interseccion--480x437.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 489px, 100vw\" \/><figcaption class=\"wp-element-caption\"><strong>Pasamos de 3D a 2D seccionando.&nbsp;<\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo de la actividad es conseguir los cuadril\u00e1teros identific\u00e1ndolos  y justificando su respuesta, explicando c\u00f3mo son.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la herramienta intersecci\u00f3n seccionamos poliedros con un plano para obtener los diferentes cuadril\u00e1teros. Pueden conseguir todos los cuadril\u00e1teros. Esta actividad permite adaptarla a diferentes niveles de dificultad, eligiendo un poliedro u otro. Las situaciones abiertas, como esta actividad, en las que no hay una \u00fanica respuesta, son ocasiones muy favorables para informarnos del nivel de profundidad al que cada estudiante es capaz de llegar (Alonso y Salar, 1992).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Escena de trabajo y sus elementos<\/strong>:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"949\" height=\"415\" src=\"https:\/\/www2.ual.es\/neotrie\/wp-content\/uploads\/2023\/06\/Escena-y-sus-elementos.jpg\" alt=\"\" class=\"wp-image-8792\" srcset=\"https:\/\/www2.ual.es\/neotrie\/wp-content\/uploads\/2023\/06\/Escena-y-sus-elementos.jpg 949w, https:\/\/www2.ual.es\/neotrie\/wp-content\/uploads\/2023\/06\/Escena-y-sus-elementos-480x210.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 949px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, se describen brevemente los pasos para su realizaci\u00f3n junto con ejemplos de errores que se pueden encontrar. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www2.ual.es\/neotrie\/wp-content\/uploads\/2023\/06\/imagen-4.png\" alt=\"\" class=\"wp-image-8795\" width=\"831\" height=\"902\" srcset=\"https:\/\/www2.ual.es\/neotrie\/wp-content\/uploads\/2023\/06\/imagen-4.png 831w, https:\/\/www2.ual.es\/neotrie\/wp-content\/uploads\/2023\/06\/imagen-4-480x521.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 831px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Agradecimientos: <em><em>Proyecto de Investigaci\u00f3n educativa PIV-055\/21, de la Junta de Andaluc\u00eda, y Proyecto UAL2020-SEJ-B2086, FEDER-Junta de Andaluc\u00eda. <\/em><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":71,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[10,154,11],"tags":[],"class_list":["post-8790","post","type-post","status-publish","format-standard","hentry","category-primaria","category-research","category-secundaria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Esta actividad forma parte del proyecto \u201cAprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D\u201c. El objetivo de la actividad es conseguir los cuadril\u00e1teros identific\u00e1ndolos y justificando su respuesta, explicando c\u00f3mo son. Con la herramienta intersecci\u00f3n seccionamos poliedros con un plano para obtener los diferentes cuadril\u00e1teros. Pueden conseguir todos los cuadril\u00e1teros. Esta actividad permite adaptarla a\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Carmen Santos Morales Rodr\u00edguez\"\/>\n\t<meta name=\"google-site-verification\" content=\"google-site-verification=yECM5sD2Ii3xsSoDBArqBmNdlDrmXh-FAAOQ40keSr4\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Neotrie VR - NeoTrie VR es un software de realidad virtual y mixta, multijugador, que permite al usuario crear, manipular e interactuar con objetos geom\u00e9tricos y modelos 3D en general.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Cortes con el plano. De 3D a 2D. - Neotrie VR\" \/>\n\t\t<meta property=\"og:description\" content=\"Esta actividad forma parte del proyecto \u201cAprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D\u201c. El objetivo de la actividad es conseguir los cuadril\u00e1teros identific\u00e1ndolos y justificando su respuesta, explicando c\u00f3mo son. Con la herramienta intersecci\u00f3n seccionamos poliedros con un plano para obtener los diferentes cuadril\u00e1teros. Pueden conseguir todos los cuadril\u00e1teros. Esta actividad permite adaptarla a\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-06-29T19:45:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-05-27T10:47:43+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/neotrie\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NeotrieVR\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Cortes con el plano. De 3D a 2D. - Neotrie VR\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Esta actividad forma parte del proyecto \u201cAprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D\u201c. El objetivo de la actividad es conseguir los cuadril\u00e1teros identific\u00e1ndolos y justificando su respuesta, explicando c\u00f3mo son. Con la herramienta intersecci\u00f3n seccionamos poliedros con un plano para obtener los diferentes cuadril\u00e1teros. Pueden conseguir todos los cuadril\u00e1teros. Esta actividad permite adaptarla a\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@NeotrieVR\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/cortes-con-el-plano-de-3d-a-2d\\\/#blogposting\",\"name\":\"Cortes con el plano. De 3D a 2D. - Neotrie VR\",\"headline\":\"Cortes con el plano. De 3D a 2D.\",\"author\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/author\\\/cmr373\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Vertices-resultantes-de-la-interseccion-.jpg\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/cortes-con-el-plano-de-3d-a-2d\\\/#articleImage\",\"width\":489,\"height\":445},\"datePublished\":\"2023-06-29T20:45:49+01:00\",\"dateModified\":\"2026-05-27T11:47:43+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/cortes-con-el-plano-de-3d-a-2d\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/cortes-con-el-plano-de-3d-a-2d\\\/#webpage\"},\"articleSection\":\"Primaria, Research, Secundaria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/cortes-con-el-plano-de-3d-a-2d\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/category\\\/primaria\\\/#listItem\",\"name\":\"Primaria\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/category\\\/primaria\\\/#listItem\",\"position\":2,\"name\":\"Primaria\",\"item\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/category\\\/primaria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/cortes-con-el-plano-de-3d-a-2d\\\/#listItem\",\"name\":\"Cortes con el plano. De 3D a 2D.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/cortes-con-el-plano-de-3d-a-2d\\\/#listItem\",\"position\":3,\"name\":\"Cortes con el plano. De 3D a 2D.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/category\\\/primaria\\\/#listItem\",\"name\":\"Primaria\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/#organization\",\"name\":\"Neotrie VR\",\"description\":\"NeoTrie VR es un software de realidad virtual y mixta, multijugador, que permite al usuario crear, manipular e interactuar con objetos geom\\u00e9tricos y modelos 3D en general.\",\"url\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/\",\"telephone\":\"+34617666437\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo-Nuevo-NeoTrie-VR.jpeg\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/cortes-con-el-plano-de-3d-a-2d\\\/#organizationLogo\",\"width\":311,\"height\":311},\"image\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/cortes-con-el-plano-de-3d-a-2d\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/neotrie\",\"https:\\\/\\\/twitter.com\\\/NeotrieVR\",\"https:\\\/\\\/www.instagram.com\\\/neotrievr\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCn7vETd_lSC3ZiT9Xgo4FTA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/author\\\/cmr373\\\/#author\",\"url\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/author\\\/cmr373\\\/\",\"name\":\"Carmen Santos Morales Rodr\\u00edguez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/cortes-con-el-plano-de-3d-a-2d\\\/#authorImage\",\"url\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/wp-content\\\/plugins\\\/ultimate-member\\\/assets\\\/img\\\/default_avatar.jpg\",\"width\":96,\"height\":96,\"caption\":\"Carmen Santos Morales Rodr\\u00edguez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/cortes-con-el-plano-de-3d-a-2d\\\/#webpage\",\"url\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/cortes-con-el-plano-de-3d-a-2d\\\/\",\"name\":\"Cortes con el plano. De 3D a 2D. - Neotrie VR\",\"description\":\"Esta actividad forma parte del proyecto \\u201cAprendizaje de los cuadril\\u00e1teros a trav\\u00e9s del 3D\\u201c. El objetivo de la actividad es conseguir los cuadril\\u00e1teros identific\\u00e1ndolos y justificando su respuesta, explicando c\\u00f3mo son. Con la herramienta intersecci\\u00f3n seccionamos poliedros con un plano para obtener los diferentes cuadril\\u00e1teros. Pueden conseguir todos los cuadril\\u00e1teros. Esta actividad permite adaptarla a\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/cortes-con-el-plano-de-3d-a-2d\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/author\\\/cmr373\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/author\\\/cmr373\\\/#author\"},\"datePublished\":\"2023-06-29T20:45:49+01:00\",\"dateModified\":\"2026-05-27T11:47:43+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/#website\",\"url\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/\",\"name\":\"Neotrie VR\",\"description\":\"NeoTrie VR es un software de realidad virtual y mixta, multijugador, que permite al usuario crear, manipular e interactuar con objetos geom\\u00e9tricos y modelos 3D en general.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www2.ual.es\\\/neotrie\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Cortes con el plano. De 3D a 2D. - Neotrie VR","description":"Esta actividad forma parte del proyecto \u201cAprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D\u201c. El objetivo de la actividad es conseguir los cuadril\u00e1teros identific\u00e1ndolos y justificando su respuesta, explicando c\u00f3mo son. Con la herramienta intersecci\u00f3n seccionamos poliedros con un plano para obtener los diferentes cuadril\u00e1teros. Pueden conseguir todos los cuadril\u00e1teros. Esta actividad permite adaptarla a","canonical_url":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"google-site-verification=yECM5sD2Ii3xsSoDBArqBmNdlDrmXh-FAAOQ40keSr4","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/#blogposting","name":"Cortes con el plano. De 3D a 2D. - Neotrie VR","headline":"Cortes con el plano. De 3D a 2D.","author":{"@id":"https:\/\/www2.ual.es\/neotrie\/author\/cmr373\/#author"},"publisher":{"@id":"https:\/\/www2.ual.es\/neotrie\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www2.ual.es\/neotrie\/wp-content\/uploads\/2023\/06\/Vertices-resultantes-de-la-interseccion-.jpg","@id":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/#articleImage","width":489,"height":445},"datePublished":"2023-06-29T20:45:49+01:00","dateModified":"2026-05-27T11:47:43+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/#webpage"},"isPartOf":{"@id":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/#webpage"},"articleSection":"Primaria, Research, Secundaria"},{"@type":"BreadcrumbList","@id":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www2.ual.es\/neotrie#listItem","position":1,"name":"Inicio","item":"https:\/\/www2.ual.es\/neotrie","nextItem":{"@type":"ListItem","@id":"https:\/\/www2.ual.es\/neotrie\/category\/primaria\/#listItem","name":"Primaria"}},{"@type":"ListItem","@id":"https:\/\/www2.ual.es\/neotrie\/category\/primaria\/#listItem","position":2,"name":"Primaria","item":"https:\/\/www2.ual.es\/neotrie\/category\/primaria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/#listItem","name":"Cortes con el plano. De 3D a 2D."},"previousItem":{"@type":"ListItem","@id":"https:\/\/www2.ual.es\/neotrie#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/#listItem","position":3,"name":"Cortes con el plano. De 3D a 2D.","previousItem":{"@type":"ListItem","@id":"https:\/\/www2.ual.es\/neotrie\/category\/primaria\/#listItem","name":"Primaria"}}]},{"@type":"Organization","@id":"https:\/\/www2.ual.es\/neotrie\/#organization","name":"Neotrie VR","description":"NeoTrie VR es un software de realidad virtual y mixta, multijugador, que permite al usuario crear, manipular e interactuar con objetos geom\u00e9tricos y modelos 3D en general.","url":"https:\/\/www2.ual.es\/neotrie\/","telephone":"+34617666437","logo":{"@type":"ImageObject","url":"https:\/\/www2.ual.es\/neotrie\/wp-content\/uploads\/2023\/05\/Logo-Nuevo-NeoTrie-VR.jpeg","@id":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/#organizationLogo","width":311,"height":311},"image":{"@id":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/neotrie","https:\/\/twitter.com\/NeotrieVR","https:\/\/www.instagram.com\/neotrievr","https:\/\/www.youtube.com\/channel\/UCn7vETd_lSC3ZiT9Xgo4FTA"]},{"@type":"Person","@id":"https:\/\/www2.ual.es\/neotrie\/author\/cmr373\/#author","url":"https:\/\/www2.ual.es\/neotrie\/author\/cmr373\/","name":"Carmen Santos Morales Rodr\u00edguez","image":{"@type":"ImageObject","@id":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/#authorImage","url":"https:\/\/www2.ual.es\/neotrie\/wp-content\/plugins\/ultimate-member\/assets\/img\/default_avatar.jpg","width":96,"height":96,"caption":"Carmen Santos Morales Rodr\u00edguez"}},{"@type":"WebPage","@id":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/#webpage","url":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/","name":"Cortes con el plano. De 3D a 2D. - Neotrie VR","description":"Esta actividad forma parte del proyecto \u201cAprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D\u201c. El objetivo de la actividad es conseguir los cuadril\u00e1teros identific\u00e1ndolos y justificando su respuesta, explicando c\u00f3mo son. Con la herramienta intersecci\u00f3n seccionamos poliedros con un plano para obtener los diferentes cuadril\u00e1teros. Pueden conseguir todos los cuadril\u00e1teros. Esta actividad permite adaptarla a","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www2.ual.es\/neotrie\/#website"},"breadcrumb":{"@id":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/#breadcrumblist"},"author":{"@id":"https:\/\/www2.ual.es\/neotrie\/author\/cmr373\/#author"},"creator":{"@id":"https:\/\/www2.ual.es\/neotrie\/author\/cmr373\/#author"},"datePublished":"2023-06-29T20:45:49+01:00","dateModified":"2026-05-27T11:47:43+01:00"},{"@type":"WebSite","@id":"https:\/\/www2.ual.es\/neotrie\/#website","url":"https:\/\/www2.ual.es\/neotrie\/","name":"Neotrie VR","description":"NeoTrie VR es un software de realidad virtual y mixta, multijugador, que permite al usuario crear, manipular e interactuar con objetos geom\u00e9tricos y modelos 3D en general.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www2.ual.es\/neotrie\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Neotrie VR - NeoTrie VR es un software de realidad virtual y mixta, multijugador, que permite al usuario crear, manipular e interactuar con objetos geom\u00e9tricos y modelos 3D en general.","og:type":"article","og:title":"Cortes con el plano. De 3D a 2D. - Neotrie VR","og:description":"Esta actividad forma parte del proyecto \u201cAprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D\u201c. El objetivo de la actividad es conseguir los cuadril\u00e1teros identific\u00e1ndolos y justificando su respuesta, explicando c\u00f3mo son. Con la herramienta intersecci\u00f3n seccionamos poliedros con un plano para obtener los diferentes cuadril\u00e1teros. Pueden conseguir todos los cuadril\u00e1teros. Esta actividad permite adaptarla a","og:url":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/","article:published_time":"2023-06-29T19:45:49+00:00","article:modified_time":"2026-05-27T10:47:43+00:00","article:publisher":"https:\/\/www.facebook.com\/neotrie","twitter:card":"summary_large_image","twitter:site":"@NeotrieVR","twitter:title":"Cortes con el plano. De 3D a 2D. - Neotrie VR","twitter:description":"Esta actividad forma parte del proyecto \u201cAprendizaje de los cuadril\u00e1teros a trav\u00e9s del 3D\u201c. El objetivo de la actividad es conseguir los cuadril\u00e1teros identific\u00e1ndolos y justificando su respuesta, explicando c\u00f3mo son. Con la herramienta intersecci\u00f3n seccionamos poliedros con un plano para obtener los diferentes cuadril\u00e1teros. Pueden conseguir todos los cuadril\u00e1teros. Esta actividad permite adaptarla a","twitter:creator":"@NeotrieVR"},"aioseo_meta_data":{"post_id":"8790","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-06-29 19:28:25","updated":"2026-05-27 11:44:13","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www2.ual.es\/neotrie\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www2.ual.es\/neotrie\/category\/primaria\/\" title=\"Primaria\">Primaria<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCortes con el plano. De 3D a 2D.\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www2.ual.es\/neotrie"},{"label":"Primaria","link":"https:\/\/www2.ual.es\/neotrie\/category\/primaria\/"},{"label":"Cortes con el plano. De 3D a 2D.","link":"https:\/\/www2.ual.es\/neotrie\/cortes-con-el-plano-de-3d-a-2d\/"}],"views":971,"_links":{"self":[{"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/posts\/8790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/users\/71"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/comments?post=8790"}],"version-history":[{"count":4,"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/posts\/8790\/revisions"}],"predecessor-version":[{"id":11813,"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/posts\/8790\/revisions\/11813"}],"wp:attachment":[{"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/media?parent=8790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/categories?post=8790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.ual.es\/neotrie\/wp-json\/wp\/v2\/tags?post=8790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}